{"id":724,"date":"2017-11-30T10:51:20","date_gmt":"2017-11-30T10:51:20","guid":{"rendered":"https:\/\/vinstofa.fridheimar.is\/home\/"},"modified":"2026-08-13T10:23:31","modified_gmt":"2026-08-13T10:23:31","slug":"home","status":"publish","type":"page","link":"https:\/\/vinstofa.fridheimar.is\/en\/","title":{"rendered":"Home"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"page-elements.php","meta":{"_acf_changed":false,"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","footnotes":""},"class_list":["post-724","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/vinstofa.fridheimar.is\/en\/wp-json\/wp\/v2\/pages\/724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinstofa.fridheimar.is\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vinstofa.fridheimar.is\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vinstofa.fridheimar.is\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vinstofa.fridheimar.is\/en\/wp-json\/wp\/v2\/comments?post=724"}],"version-history":[{"count":0,"href":"https:\/\/vinstofa.fridheimar.is\/en\/wp-json\/wp\/v2\/pages\/724\/revisions"}],"wp:attachment":[{"href":"https:\/\/vinstofa.fridheimar.is\/en\/wp-json\/wp\/v2\/media?parent=724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}